{"id":8950,"date":"2025-06-12T12:33:43","date_gmt":"2025-06-12T10:33:43","guid":{"rendered":"https:\/\/www.pointbreakschool.com\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/"},"modified":"2025-06-12T12:33:43","modified_gmt":"2025-06-12T10:33:43","slug":"wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2","status":"publish","type":"post","link":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/","title":{"rendered":"Wo kann man auf den Kanarischen Inseln surfen? Die 5 besten Spots"},"content":{"rendered":"<h2>Von Fuerteventura bis Gran Canaria gibt es jede Menge Str\u00e4nde, die bei Surfern wegen ihrer Wellen beliebt sind: und keinen Mangel an Surfschulen, in denen Sie das Reiten der Wellen lernen k\u00f6nnen.<\/h2>\n<p><strong>Warum lieben die Surfer die Kanarischen Inseln?<\/strong> Ganz einfach: Diese wundersch\u00f6nen Inseln bieten <strong>ideale Bedingungen zum Surfen<\/strong>, und Surfer wissen, dass sie in Europa kaum bessere finden k\u00f6nnen. Die g\u00fcnstigen klimatischen Bedingungen (subtropisches Klima), die Wellen des Atlantischen Ozeans, die milde Wassertemperatur und vor allem eine ausgepr\u00e4gte Wassersportkultur, zu der auch das Surfen geh\u00f6rt, machen die Kanarischen Inseln zu einem privilegierten Ort, um diesen faszinierenden Sport auszu\u00fcben&#8230; das ganze Jahr \u00fcber. <\/p>\n<p>Lassen Sie uns also herausfinden, welches die <strong>5 Szenarien oder besser gesagt die 5 Orte sind, die<\/strong> <strong>Sie<\/strong> auf den Kanarischen Inseln <strong>nicht verpassen d\u00fcrfen<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5404 size-full\" src=\"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo.jpg\" alt=\"Surfer bereiten sich auf den Cotill PointBreak vor\" width=\"800\" height=\"555\" srcset=\"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo.jpg 800w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo-300x208.jpg 300w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo-768x533.jpg 768w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo-210x146.jpg 210w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo-50x35.jpg 50w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo-576x400.jpg 576w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfisti-el-cotillo-108x75.jpg 108w\" sizes=\"auto, (max-width:767px) 480px, (max-width:800px) 100vw, 800px\" \/><\/p>\n<h3>Surfen auf den Kanarischen Inseln: die 5 Must-See-Spots<\/h3>\n<p>Beginnen wir mit der Surferinsel schlechthin, <strong>Fuerteventura<\/strong>: Ihre ber\u00fchmtesten Str\u00e4nde, Playa de Corralejo, Punta Elena, El Cotillo und Playa de Cofete, bieten <strong>Wellen \u201ef\u00fcr jeden Geschmack\u201c<\/strong>, nicht zu vergessen La Burbuja am Strand von El Hierro, wo eine Lavabarriere perfekte Bedingungen zum Surfen schafft. Sowohl Anf\u00e4nger als auch Experten finden hier geeignete Wellen f\u00fcr ein befriedigendes und sogar aufregendes Erlebnis! Und Sie k\u00f6nnen sich sogar einer <a href=\"https:\/\/www.pointbreakschool.com\/de\/kite-surf-kurse\/\">Kitesurfing-Schule auf Fuerteventura<\/a> anschlie\u00dfen und eine lustige und spektakul\u00e4re Disziplin ausprobieren.  <\/p>\n<p><strong>Teneriffa<\/strong> steht dem in nichts nach: Die Str\u00e4nde von Las Am\u00e9ricas, El M\u00e9dano, La Izquierda und Bajamar sind <strong>das ganze Jahr \u00fcber<\/strong> perfekt zum <strong>Surfen<\/strong> geeignet, auch dank des milden Klimas (wie auf allen Kanaren). Surfer kennen <strong>Lanzarote<\/strong> gut, ber\u00fchmt f\u00fcr seinen langen Famara-Strand, der vor allem f\u00fcr erfahrene Surfer die perfekte Welle zum Surfen bietet. <\/p>\n<p><strong>Gran Canaria<\/strong> bietet Str\u00e4nde wie Playa del Ingl\u00e9s und Las Canteras mit einer <strong>Vielzahl von Wellen<\/strong>, die sowohl f\u00fcr Anf\u00e4nger als auch f\u00fcr erfahrene Surfer geeignet sind. Und diejenigen, die das Surfen lernen m\u00f6chten, k\u00f6nnen sich einer der vielen Surfschulen anschlie\u00dfen. <\/p>\n<p>Apropos Las Canteras: Wir empfehlen Ihnen <strong>La Cicer<\/strong>, das am westlichen Teil des Strandes liegt. Hier finden Sie nicht nur die \u201eperfekten\u201c Wellen, sondern auch die richtige Atmosph\u00e4re und den besten Service zum Surfen.<\/p>\n<p>Auf Gran Canaria befindet sich auch <strong>El Confital<\/strong>, nur 10 Autominuten von Las Palmas de Gran Canaria entfernt. Dieser Strand wird von Fans wegen seiner kraftvollen und schnellen Wellen als einer der besten Surfstr\u00e4nde Europas eingestuft: Viele Menschen str\u00f6men zu diesem Strand, um die perfekte Welle zu finden.<\/p>\n<p><strong>La Palma<\/strong> ist ein weiteres beliebtes Ziel f\u00fcr Surfer, die mit den Wellen <strong>an den Str\u00e4nden von Puntagorda und Charco Verde<\/strong> vertraut sind. Hier befindet sich auch der Strand von Nogales im Nordosten der Insel La Palma, der sich durch seinen schwarzen Vulkansand und perfekte Wellen f\u00fcr erfahrene Surfer auszeichnet, die die starken Str\u00f6mungen zu meistern wissen. <\/p>\n<p><strong>La Gomera<\/strong> ist eine Insel, die einige Perlen birgt: Wir sprechen von absolut un\u00fcbersehbaren Buchten f\u00fcr diejenigen, die das Surfen im Blut haben.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5409 size-full\" src=\"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda.jpg\" alt=\"Surfer reitet auf einer Welle | PointBreak\" width=\"800\" height=\"533\" srcset=\"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda.jpg 800w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda-300x200.jpg 300w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda-768x512.jpg 768w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda-219x146.jpg 219w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda-50x33.jpg 50w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda-576x384.jpg 576w, https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/surfista-cavalca-onda-113x75.jpg 113w\" sizes=\"auto, (max-width:767px) 480px, (max-width:800px) 100vw, 800px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Wann ist die beste Zeit zum Surfen auf den Kanarischen Inseln?<\/h3>\n<p>Die ideale Zeit zum Surfen auf den Kanarischen Inseln <strong>ist von September bis April<\/strong>, wenn die Wetterbedingungen perfekt sind, mit angenehmen Temperaturen und nicht zu \u00fcberf\u00fcllten Str\u00e4nden. <strong>Im Winter jedoch ziehen die gro\u00dfen Wellen die erfahrensten Surfer an<\/strong>, w\u00e4hrend der Sommer gute Wellen f\u00fcr alle Arten von Surfern bietet: Experten, Fortgeschrittene, Anf\u00e4nger&#8230; nicht zu vergessen, dass Sie in den Surf- und Kitesurfschulen immer die M\u00f6glichkeit haben, es zu lernen. <\/p>\n<h3>Zusammenfassend<\/h3>\n<p><strong>Die Kanarischen Inseln sind ein Paradies f\u00fcr Surfer<\/strong>: Sie k\u00f6nnen das ganze Jahr \u00fcber surfen, ganz gleich, ob Sie ein erfahrener Surfer oder ein Anf\u00e4nger sind.<\/p>\n<p>Die Kanarischen Inseln bieten dank der <strong>perfekten Wetterbedingungen<\/strong> und der Vielfalt der Wellen ein au\u00dfergew\u00f6hnliches Erlebnis f\u00fcr Surfer aller Niveaus. Jeder, der diesen Sport, aber auch andere Sportarten wie Kite- und Windsurfen betreiben m\u00f6chte, sollte sich ein Surfbrett schnappen, ein Flugticket kaufen und so schnell wie m\u00f6glich auf diese gl\u00fccklichen Inseln fliegen, um einige der spektakul\u00e4rsten Wellen Europas zu reiten. <\/p>\n<p>Von Fuerteventura \u00fcber La Palma bis Gran Canaria sind diese Atlantikinseln das ganze Jahr \u00fcber ein Traumziel f\u00fcr Surfer. September bis April ist die beste Zeit f\u00fcr Anf\u00e4nger und Experten, obwohl die erfahreneren Surfer gerne im Winter surfen, wenn die Wellen im Ozean gr\u00f6\u00dfer werden und die Vorstellung, die \u201eBig Wave\u201c zu reiten, die Fantasie der erfahreneren Surfer kitzelt. <\/p>\n<p>\u00dcbrigens gibt es auf den Kanarischen Inseln auch zahlreiche <strong>Surfschulen f\u00fcr Anf\u00e4nger und Profis<\/strong>, so dass sie der ideale Ort f\u00fcr diejenigen sind, die das Surfen lernen oder ihre F\u00e4higkeiten verbessern m\u00f6chten.<\/p>\n<p>M\u00f6chten Sie ein Beispiel von allen?<\/p>\n<p>Dann sind Sie hier genau richtig. Besuchen Sie <a href=\"https:\/\/www.pointbreakschool.com\/es\/\">Point Break<\/a> und finden Sie heraus, wie Sie surfen lernen oder Ihre F\u00e4higkeiten verbessern k\u00f6nnen! <\/p>\n<h3>Mitbringsel<\/h3>\n<ul>\n<li>Die Kanarischen Inseln bieten ein subtropisches Klima, milde Temperaturen und best\u00e4ndige Wellen, so dass das Surfen das ganze Jahr \u00fcber m\u00f6glich ist, ideal f\u00fcr Anf\u00e4nger und erfahrene Surfer gleicherma\u00dfen.<\/li>\n<li>Von Fuerteventura bis La Palma hat jede Insel emblematische Str\u00e4nde und Wellen, die sich an verschiedene Leistungsniveaus anpassen, von Str\u00e4nden wie La Cicer f\u00fcr Anf\u00e4nger bis zu El Confital, ber\u00fchmt f\u00fcr seine schnellen Wellen f\u00fcr Experten.<\/li>\n<li>Die ausgepr\u00e4gte Surfkultur auf den Inseln hat ein unterst\u00fctzendes Umfeld geschaffen. Zahlreiche Schulen bieten Surf-, Kitesurf- und Windsurfkurse an und machen die Insel zu einem leicht zug\u00e4nglichen Ziel f\u00fcr alle, die ihre F\u00e4higkeiten erlernen oder verbessern m\u00f6chten.<\/li>\n<li>Von September bis April sind die Wetterbedingungen optimal, mit weniger Menschenmassen und anspruchsvolleren Wellen. Im Winter ziehen die gro\u00dfen Wellen erfahrene Surfer an, w\u00e4hrend der Sommer sanftere Wellen f\u00fcr jedermann bietet. <\/li>\n<li>Die Kanarischen Inseln sind dank ihres Klimas, ihrer Vielfalt an Spots und ihrer Zug\u00e4nglichkeit eine der besten Optionen in Europa zum Surfen. Es ist ein komplettes Reiseziel sowohl f\u00fcr Adrenalins\u00fcchtige als auch f\u00fcr diejenigen, die lernen und die Umwelt genie\u00dfen m\u00f6chten. <\/li>\n<\/ul>\n<h3>FAQ<\/h3>\n<p><script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfPor qu\u00e9 los surfistas adoran las Islas Canarias?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Las Islas Canarias ofrecen condiciones ideales para el surf: un clima subtropical, olas constantes en el Atl\u00e1ntico, y una fuerte cultura de deportes n\u00e1uticos que hace de este lugar un para\u00edso para surfistas durante todo el a\u00f1o.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfCu\u00e1les son los mejores spots para surfear en las Islas Canarias?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"Las Islas Canarias tienen 5 spots imprescindibles: Fuerteventura con Corralejo y La Burbuja, Tenerife con Playa de Las Am\u00e9ricas y Bajamar, Lanzarote con Famara, Gran Canaria con Las Canteras y El Confital, y La Palma con Nogales.\"\n      }\n    },\n    {\n      \"@type\": \"Question\",\n      \"name\": \"\u00bfCu\u00e1l es la mejor \u00e9poca para surfear en Canarias?\",\n      \"acceptedAnswer\": {\n        \"@type\": \"Answer\",\n        \"text\": \"La mejor \u00e9poca para surfear en las Islas Canarias es de septiembre a abril, cuando las condiciones meteorol\u00f3gicas son \u00f3ptimas y las playas est\u00e1n menos masificadas. En invierno, las olas m\u00e1s grandes atraen a surfistas experimentados.\"\n      }\n    }\n  ]\n}\n<\/script><\/p>\n<p><strong>Warum lieben die Surfer die Kanarischen Inseln?<\/strong><\/p>\n<p>Die Kanarischen Inseln bieten ideale Bedingungen f\u00fcr das Surfen: ein subtropisches Klima, best\u00e4ndige Wellen im Atlantik und eine ausgepr\u00e4gte Wassersportkultur machen sie das ganze Jahr \u00fcber zu einem Paradies f\u00fcr Surfer.<\/p>\n<p><strong>Welches sind die besten Surfspots auf den Kanarischen Inseln?<\/strong><\/p>\n<p>Die Kanarischen Inseln haben 5 unverzichtbare Orte: Fuerteventura mit Corralejo und La Burbuja, Teneriffa mit Playa de Las Am\u00e9ricas und Bajamar, Lanzarote mit Famara, Gran Canaria mit Las Canteras und El Confital und La Palma mit Nogales.<\/p>\n<p><strong>Wann ist die beste Zeit zum Surfen auf den Kanarischen Inseln?<\/strong><\/p>\n<p>Die beste Zeit zum Surfen auf den Kanarischen Inseln ist von September bis April, wenn die Wetterbedingungen optimal sind und die Str\u00e4nde weniger \u00fcberlaufen sind. Im Winter ziehen die gr\u00f6\u00dferen Wellen erfahrene Surfer an. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Fuerteventura bis Gran Canaria gibt es jede Menge Str\u00e4nde, die bei Surfern wegen ihrer Wellen beliebt sind: und keinen Mangel an Surfschulen, in denen Sie<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":16,"featured_media":5398,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[64],"tags":[],"class_list":["post-8950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de-4"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entdecken Sie, wo man auf den Kanarischen Inseln surfen kann und die 5 besten Spots<\/title>\n<meta name=\"description\" content=\"Entdecken Sie, wo man auf den Kanarischen Inseln surfen kann, mit den besten Spots auf Fuerteventura, Teneriffa und Gran Canaria und den idealen Bedingungen zum Surfen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roberto Serra\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entdecken Sie, wo man auf den Kanarischen Inseln surfen kann und die 5 besten Spots","description":"Entdecken Sie, wo man auf den Kanarischen Inseln surfen kann, mit den besten Spots auf Fuerteventura, Teneriffa und Gran Canaria und den idealen Bedingungen zum Surfen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/","twitter_misc":{"Verfasst von":"Roberto Serra","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#article","isPartOf":{"@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/"},"author":{"name":"Roberto Serra","@id":"https:\/\/www.pointbreakschool.com\/#\/schema\/person\/992ff6b3fa29615e0194e616be27fffc"},"headline":"Wo kann man auf den Kanarischen Inseln surfen? Die 5 besten Spots","datePublished":"2025-06-12T10:33:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/"},"wordCount":1174,"commentCount":0,"publisher":{"@id":"https:\/\/www.pointbreakschool.com\/#organization"},"image":{"@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/dove-fare-surf-canarie.jpg","articleSection":["Blog"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/","url":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/","name":"Entdecken Sie, wo man auf den Kanarischen Inseln surfen kann und die 5 besten Spots","isPartOf":{"@id":"https:\/\/www.pointbreakschool.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#primaryimage"},"image":{"@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/dove-fare-surf-canarie.jpg","datePublished":"2025-06-12T10:33:43+00:00","description":"Entdecken Sie, wo man auf den Kanarischen Inseln surfen kann, mit den besten Spots auf Fuerteventura, Teneriffa und Gran Canaria und den idealen Bedingungen zum Surfen.","breadcrumb":{"@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#primaryimage","url":"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/dove-fare-surf-canarie.jpg","contentUrl":"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/dove-fare-surf-canarie.jpg","width":800,"height":533,"caption":"Dove fare surf alle Canarie | PointBreak"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pointbreakschool.com\/de\/wo-kann-man-auf-den-kanarischen-inseln-surfen-die-5-besten-spots-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pointbreakschool.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wo kann man auf den Kanarischen Inseln surfen? Die 5 besten Spots"}]},{"@type":"WebSite","@id":"https:\/\/www.pointbreakschool.com\/#website","url":"https:\/\/www.pointbreakschool.com\/","name":"","description":"","publisher":{"@id":"https:\/\/www.pointbreakschool.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pointbreakschool.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.pointbreakschool.com\/#organization","name":"Point Break Water Sports | Wet & Salty Fuerteventura S.L.","url":"https:\/\/www.pointbreakschool.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.pointbreakschool.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/2017\/04\/logo_600.png","contentUrl":"https:\/\/www.pointbreakschool.com\/wp-content\/uploads\/2017\/04\/logo_600.png","width":142,"height":142,"caption":"Point Break Water Sports | Wet & Salty Fuerteventura S.L."},"image":{"@id":"https:\/\/www.pointbreakschool.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.pointbreakschool.com\/#\/schema\/person\/992ff6b3fa29615e0194e616be27fffc","name":"Roberto Serra","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c9cf864d6090fa9af4b57f8fccc6f37c89d89106466760d8d94cbdb70ed2d068?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c9cf864d6090fa9af4b57f8fccc6f37c89d89106466760d8d94cbdb70ed2d068?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c9cf864d6090fa9af4b57f8fccc6f37c89d89106466760d8d94cbdb70ed2d068?s=96&d=mm&r=g","caption":"Roberto Serra"},"url":"https:\/\/www.pointbreakschool.com\/de\/author\/roberto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/posts\/8950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/comments?post=8950"}],"version-history":[{"count":0,"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/posts\/8950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/media\/5398"}],"wp:attachment":[{"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/media?parent=8950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/categories?post=8950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pointbreakschool.com\/de\/wp-json\/wp\/v2\/tags?post=8950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}